{"id":17059,"date":"2026-02-16T15:33:54","date_gmt":"2026-02-16T14:33:54","guid":{"rendered":"https:\/\/colomboarte.com\/dario-maglionico-dis-sequenze-liminali\/"},"modified":"2026-05-05T16:01:02","modified_gmt":"2026-05-05T14:01:02","slug":"dario-maglionico-dis-sequenze-liminali","status":"publish","type":"post","link":"https:\/\/colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/","title":{"rendered":"Dario Maglionico &#8211; Dis-sequenze Liminali"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]26 february 2026 &#8211; 3 april 2026<\/p>\n<p>Opening: marted\u00ec 26 february 2026 h. 18.00<\/p>\n<p><strong>Dario Maglionico<\/strong><\/p>\n<p><strong>Dis-sequenze Liminali <\/strong><\/p>\n<p>curated by Arianna Baldoni<\/p>\n<p>&nbsp;<\/p>\n<p>The gallery of Antonio Colombo, after 30 years of activity, has decided to change its visual identity with a new logo, a new name and a new website. The first exhibition at Colombo\u2019s Gallery opens on 26 February 2026, when the gallery is pleased to present Dis-sequenze liminali, a solo show by Dario Maglionico curated by Arianna Baldoni. The exhibition, the seventh in the cycle of collaborations with Colombo\u2019s Gallery, takes its cue from the work chosen as one of the finalists in the 24th Premio Cairo, titled Reificazione #95 (Reification #95), and brings together a series of recent works developed precisely in relation to this painting.<br \/>\nTo cross over the linear nature of time means gaining access to a dimension related to the instant, where past, present and future coexist in a plot of synchronicity, memories and mental projections.<br \/>\nThe pictorial research of Dario Maglionico exists precisely in this suspended space. For years the artist has been engaged in the exploration of multiple realities, psychic flows and inner landscapes.<br \/>\nHis works stem from the elaboration of memories and mental visualizations, initially reformulated through digital models of settings, and then transposed onto canvas with painstaking technique that strives for an honest interaction with reality. The scenes are mostly domestic interiors inhabited by solitary, sometimes evanescent figures, glimpsed in different actions that happen simultaneously within a non-linear time, where \u2013 to use the words of T.S. Eliot in Burnt Norton \u2013 \u201ctime present and time past are both perhaps present in time future.\u201d<br \/>\nMaglionico\u2019s rooms become devices of space-time overlay, places in which the viewpoints multiply themselves and perception becomes unstable. The overturned perspectives, the incongruous sequences and visual slippages generate dreamy environments that while complying with a rigorous project, allude to a reality that eludes the ordinary cognitive system.<br \/>\nThe new cycle of works by Maglionico turns around a single room, where the perspective shifts and the viewpoint reverses in a continuous spatial loop. Female figures, everyday objects, symbolic presences, surreal spaces, thresholds, filters and layers. These elements return in the artist\u2019s work, almost as if they were suggestions of primordial entities or embryos of future universes.<br \/>\nThe darkness wraps the works, interrupted by glimmers and sparks which the painted texture accentuates in the contrast between profiles in the foreground and the density of the background. In reference to the use of light, Ivan Quaroni has observed that Maglionico\u2019s painting becomes \u201cmore intelligible and seductive, without losing that sense of dreamy suspension that from the outset has been one of the earmarks of his style.\u201d<\/p>\n<p>DARIO MAGLIONICO was born in Naples in 1986. He currently lives and works in Milan. He currently lives and works in Milan. With a degree in Biomedical Engineering from the Milan Polytechnic, he concentrates exclusively on painting. Maglionico was a finalist in the Premio Fondazione VAF at the MART Museum of Modern and Contemporary Art of Trento and Rovereto, where he has shown his works. In 2020 he opened Doppelg\u00e4nger, his first solo show at the Vin Gallery of Ho Chi Minh City, Vietnam. In 2018 in Milan, he presented the solo exhibition Everyday is like Sunday, curated by Ivan Quaroni, at Colombo\u2019s Gallery, and he took part in the group show If The Walls Could Talk in London, at the Alice Black Gallery. In 2016 he collaborated with the writer Domenico Starnone, making the illustrations for the book Scherzetto published by Einaudi. In 2023 the monograph Dario Maglionico. Dove abita il tempo sospeso, edited by Nicoletta Colombo, was published by VAF-Stiftung, presented during the course of the solo exhibition FLOATING SPACE at Colombo\u2019s Gallery. In 2025 he was selected as one of the finalists in the 24th Premio Cairo, the most prestigious Italian award to support young artists under 40, organized by the monthly magazine ARTE of Cairo Editore.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing wpex-w-100 wpex-clear\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-module vcex-divider vcex-divider-solid vcex-divider-center wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-main\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing wpex-w-100 wpex-clear\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-image-grid-wrap\"><div class=\"vcex-module vcex-image-grid grid-style-default wpex-row wpex-clr wpex-lightbox-group\"><div class=\"id-17013 vcex-image-grid-entry vcex-grid-item wpex-text-center span_1_of_4 col col-1\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" data-caption=\"Reificazione #95, oil on canvas, 110 x 190 cm, 2025\"><img width=\"1485\" height=\"850\" src=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg\" class=\"wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg 1485w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025-800x458.jpg 800w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025-1200x687.jpg 1200w\" sizes=\"auto, (max-width: 1485px) 100vw, 1485px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-17011 vcex-image-grid-entry vcex-grid-item wpex-text-center span_1_of_4 col col-2\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-94-oil-on-canvas-140-x-247-cm-2025.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"1503\" height=\"850\" src=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-94-oil-on-canvas-140-x-247-cm-2025.jpg\" class=\"wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-94-oil-on-canvas-140-x-247-cm-2025.jpg 1503w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-94-oil-on-canvas-140-x-247-cm-2025-800x452.jpg 800w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-94-oil-on-canvas-140-x-247-cm-2025-1200x679.jpg 1200w\" sizes=\"auto, (max-width: 1503px) 100vw, 1503px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-17003 vcex-image-grid-entry vcex-grid-item wpex-text-center span_1_of_4 col col-3\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-10-oil-on-canvas-35-x-60-cm-2025-1.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"850\" height=\"498\" src=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-10-oil-on-canvas-35-x-60-cm-2025-1.jpg\" class=\"wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-10-oil-on-canvas-35-x-60-cm-2025-1.jpg 850w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-10-oil-on-canvas-35-x-60-cm-2025-1-800x469.jpg 800w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-17009 vcex-image-grid-entry vcex-grid-item wpex-text-center span_1_of_4 col col-4\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-13-oil-on-canvas-60-x-100-cm-2025.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"1421\" height=\"850\" src=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-13-oil-on-canvas-60-x-100-cm-2025.jpg\" class=\"wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-13-oil-on-canvas-60-x-100-cm-2025.jpg 1421w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-13-oil-on-canvas-60-x-100-cm-2025-800x479.jpg 800w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-13-oil-on-canvas-60-x-100-cm-2025-1200x718.jpg 1200w\" sizes=\"auto, (max-width: 1421px) 100vw, 1421px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-17005 vcex-image-grid-entry vcex-grid-item wpex-text-center span_1_of_4 col col-1\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-11-oil-on-canvas-50-x-60-cm-2025.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"1024\" height=\"850\" src=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-11-oil-on-canvas-50-x-60-cm-2025.jpg\" class=\"wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-11-oil-on-canvas-50-x-60-cm-2025.jpg 1024w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-11-oil-on-canvas-50-x-60-cm-2025-800x664.jpg 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-17007 vcex-image-grid-entry vcex-grid-item wpex-text-center span_1_of_4 col col-2\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-12-oil-on-canvas-60-x-100-cm-2025.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"1418\" height=\"850\" src=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-12-oil-on-canvas-60-x-100-cm-2025.jpg\" class=\"wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-12-oil-on-canvas-60-x-100-cm-2025.jpg 1418w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-12-oil-on-canvas-60-x-100-cm-2025-800x480.jpg 800w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Acausality-12-oil-on-canvas-60-x-100-cm-2025-1200x719.jpg 1200w\" sizes=\"auto, (max-width: 1418px) 100vw, 1418px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-17015 vcex-image-grid-entry vcex-grid-item wpex-text-center span_1_of_4 col col-3\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-96-oil-on-canvas-80-x-60-cm-2026-scaled.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"1913\" height=\"2560\" src=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-96-oil-on-canvas-80-x-60-cm-2026-scaled.jpg\" class=\"wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-96-oil-on-canvas-80-x-60-cm-2026-scaled.jpg 1913w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-96-oil-on-canvas-80-x-60-cm-2026-598x800.jpg 598w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-96-oil-on-canvas-80-x-60-cm-2026-897x1200.jpg 897w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-96-oil-on-canvas-80-x-60-cm-2026-1148x1536.jpg 1148w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-96-oil-on-canvas-80-x-60-cm-2026-1530x2048.jpg 1530w\" sizes=\"auto, (max-width: 1913px) 100vw, 1913px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-17017 vcex-image-grid-entry vcex-grid-item wpex-text-center span_1_of_4 col col-4\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-97-oil-on-canvas-80-x-60-cm-2026-scaled.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"1924\" height=\"2560\" src=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-97-oil-on-canvas-80-x-60-cm-2026-scaled.jpg\" class=\"wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-97-oil-on-canvas-80-x-60-cm-2026-scaled.jpg 1924w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-97-oil-on-canvas-80-x-60-cm-2026-601x800.jpg 601w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-97-oil-on-canvas-80-x-60-cm-2026-902x1200.jpg 902w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-97-oil-on-canvas-80-x-60-cm-2026-1154x1536.jpg 1154w, https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-97-oil-on-canvas-80-x-60-cm-2026-1539x2048.jpg 1539w\" sizes=\"auto, (max-width: 1924px) 100vw, 1924px\" \/><\/a><\/div><\/figure><\/div><\/div><\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]26 february 2026 &#8211; 3 april 2026 Opening: marted\u00ec 26 february 2026 h. 18.00 Dario Maglionico Dis-sequenze Liminali curated by Arianna Baldoni &nbsp; The gallery of Antonio Colombo, after 30 years of activity, has decided to change its visual identity with a new logo, a new name and a new website. The first exhibition&hellip;<\/p>\n","protected":false},"author":2,"featured_media":17013,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1888],"tags":[],"post_series":[],"class_list":["post-17059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-year-2026","entry","no-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dario Maglionico - Dis-sequenze Liminali - COLOMBO&#039;S GALLERY<\/title>\n<meta name=\"description\" content=\"Dario Maglionico Dis-sequenze liminali curated by Arianna Baldoni 26 february 2026 - 3 april 2026 Opening: gioved\u00ec 26 febbraio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dario Maglionico - Dis-sequenze Liminali - COLOMBO&#039;S GALLERY\" \/>\n<meta property=\"og:description\" content=\"Dario Maglionico Dis-sequenze liminali curated by Arianna Baldoni 26 february 2026 - 3 april 2026 Opening: gioved\u00ec 26 febbraio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/\" \/>\n<meta property=\"og:site_name\" content=\"COLOMBO&#039;S GALLERY\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-16T14:33:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T14:01:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1485\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diletta\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"diletta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/\"},\"author\":{\"name\":\"diletta\",\"@id\":\"https:\\\/\\\/colomboarte.com\\\/#\\\/schema\\\/person\\\/c3297bb881dea62131ce8567b86be52b\"},\"headline\":\"Dario Maglionico &#8211; Dis-sequenze Liminali\",\"datePublished\":\"2026-02-16T14:33:54+00:00\",\"dateModified\":\"2026-05-05T14:01:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/\"},\"wordCount\":709,\"publisher\":{\"@id\":\"https:\\\/\\\/colomboarte.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colomboarte.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg\",\"articleSection\":[\"Year 2026\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/\",\"url\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/\",\"name\":\"Dario Maglionico - Dis-sequenze Liminali - COLOMBO&#039;S GALLERY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colomboarte.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colomboarte.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg\",\"datePublished\":\"2026-02-16T14:33:54+00:00\",\"dateModified\":\"2026-05-05T14:01:02+00:00\",\"description\":\"Dario Maglionico Dis-sequenze liminali curated by Arianna Baldoni 26 february 2026 - 3 april 2026 Opening: gioved\u00ec 26 febbraio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colomboarte.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/colomboarte.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg\",\"width\":1485,\"height\":850,\"caption\":\"Reificazione #95, oil on canvas, 110 x 190 cm, 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/dario-maglionico-dis-sequenze-liminali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.colomboarte.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dario Maglionico &#8211; Dis-sequenze Liminali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colomboarte.com\\\/#website\",\"url\":\"https:\\\/\\\/colomboarte.com\\\/\",\"name\":\"COLOMBO&#039;S GALLERY\",\"description\":\"Galleria d&#039;Arte Contemporanea\",\"publisher\":{\"@id\":\"https:\\\/\\\/colomboarte.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colomboarte.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colomboarte.com\\\/#organization\",\"name\":\"COLOMBO&#039;S GALLERY\",\"url\":\"https:\\\/\\\/colomboarte.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/colomboarte.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/colomboarte.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/colombos-gallery-logo-homepage-scaled.png\",\"contentUrl\":\"https:\\\/\\\/colomboarte.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/colombos-gallery-logo-homepage-scaled.png\",\"width\":353,\"height\":2560,\"caption\":\"COLOMBO&#039;S GALLERY\"},\"image\":{\"@id\":\"https:\\\/\\\/colomboarte.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/colomboarte.com\\\/#\\\/schema\\\/person\\\/c3297bb881dea62131ce8567b86be52b\",\"name\":\"diletta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e58f114e72ade3e1cc323ec8623c1732f92ee1cbddb17b0a361191f25a760fb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e58f114e72ade3e1cc323ec8623c1732f92ee1cbddb17b0a361191f25a760fb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e58f114e72ade3e1cc323ec8623c1732f92ee1cbddb17b0a361191f25a760fb0?s=96&d=mm&r=g\",\"caption\":\"diletta\"},\"url\":\"https:\\\/\\\/colomboarte.com\\\/en\\\/author\\\/chiara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dario Maglionico - Dis-sequenze Liminali - COLOMBO&#039;S GALLERY","description":"Dario Maglionico Dis-sequenze liminali curated by Arianna Baldoni 26 february 2026 - 3 april 2026 Opening: gioved\u00ec 26 febbraio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/","og_locale":"en_US","og_type":"article","og_title":"Dario Maglionico - Dis-sequenze Liminali - COLOMBO&#039;S GALLERY","og_description":"Dario Maglionico Dis-sequenze liminali curated by Arianna Baldoni 26 february 2026 - 3 april 2026 Opening: gioved\u00ec 26 febbraio","og_url":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/","og_site_name":"COLOMBO&#039;S GALLERY","article_published_time":"2026-02-16T14:33:54+00:00","article_modified_time":"2026-05-05T14:01:02+00:00","og_image":[{"width":1485,"height":850,"url":"https:\/\/www.colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg","type":"image\/jpeg"}],"author":"diletta","twitter_misc":{"Written by":"diletta","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/#article","isPartOf":{"@id":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/"},"author":{"name":"diletta","@id":"https:\/\/colomboarte.com\/#\/schema\/person\/c3297bb881dea62131ce8567b86be52b"},"headline":"Dario Maglionico &#8211; Dis-sequenze Liminali","datePublished":"2026-02-16T14:33:54+00:00","dateModified":"2026-05-05T14:01:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/"},"wordCount":709,"publisher":{"@id":"https:\/\/colomboarte.com\/#organization"},"image":{"@id":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/#primaryimage"},"thumbnailUrl":"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg","articleSection":["Year 2026"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/","url":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/","name":"Dario Maglionico - Dis-sequenze Liminali - COLOMBO&#039;S GALLERY","isPartOf":{"@id":"https:\/\/colomboarte.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/#primaryimage"},"image":{"@id":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/#primaryimage"},"thumbnailUrl":"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg","datePublished":"2026-02-16T14:33:54+00:00","dateModified":"2026-05-05T14:01:02+00:00","description":"Dario Maglionico Dis-sequenze liminali curated by Arianna Baldoni 26 february 2026 - 3 april 2026 Opening: gioved\u00ec 26 febbraio","breadcrumb":{"@id":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/#primaryimage","url":"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg","contentUrl":"https:\/\/colomboarte.com\/wp-content\/uploads\/2026\/02\/Reificazione-95-oil-on-canvas-110-x-190-cm-2025.jpg","width":1485,"height":850,"caption":"Reificazione #95, oil on canvas, 110 x 190 cm, 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/www.colomboarte.com\/en\/dario-maglionico-dis-sequenze-liminali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colomboarte.com\/en\/"},{"@type":"ListItem","position":2,"name":"Dario Maglionico &#8211; Dis-sequenze Liminali"}]},{"@type":"WebSite","@id":"https:\/\/colomboarte.com\/#website","url":"https:\/\/colomboarte.com\/","name":"COLOMBO&#039;S GALLERY","description":"Galleria d&#039;Arte Contemporanea","publisher":{"@id":"https:\/\/colomboarte.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colomboarte.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/colomboarte.com\/#organization","name":"COLOMBO&#039;S GALLERY","url":"https:\/\/colomboarte.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/colomboarte.com\/#\/schema\/logo\/image\/","url":"https:\/\/colomboarte.com\/wp-content\/uploads\/2025\/12\/colombos-gallery-logo-homepage-scaled.png","contentUrl":"https:\/\/colomboarte.com\/wp-content\/uploads\/2025\/12\/colombos-gallery-logo-homepage-scaled.png","width":353,"height":2560,"caption":"COLOMBO&#039;S GALLERY"},"image":{"@id":"https:\/\/colomboarte.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/colomboarte.com\/#\/schema\/person\/c3297bb881dea62131ce8567b86be52b","name":"diletta","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e58f114e72ade3e1cc323ec8623c1732f92ee1cbddb17b0a361191f25a760fb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e58f114e72ade3e1cc323ec8623c1732f92ee1cbddb17b0a361191f25a760fb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e58f114e72ade3e1cc323ec8623c1732f92ee1cbddb17b0a361191f25a760fb0?s=96&d=mm&r=g","caption":"diletta"},"url":"https:\/\/colomboarte.com\/en\/author\/chiara\/"}]}},"_links":{"self":[{"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/posts\/17059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/comments?post=17059"}],"version-history":[{"count":6,"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/posts\/17059\/revisions"}],"predecessor-version":[{"id":17223,"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/posts\/17059\/revisions\/17223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/media\/17013"}],"wp:attachment":[{"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/media?parent=17059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/categories?post=17059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/tags?post=17059"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/colomboarte.com\/en\/wp-json\/wp\/v2\/post_series?post=17059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}